{"id":20861,"date":"2022-11-17T11:08:26","date_gmt":"2022-11-17T14:08:26","guid":{"rendered":"https:\/\/warren.com.br\/magazine\/?p=20861"},"modified":"2023-08-02T22:15:39","modified_gmt":"2023-08-03T01:15:39","slug":"wsec11-fii-warren","status":"publish","type":"post","link":"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/","title":{"rendered":"WSEC11: conhe\u00e7a o primeiro fundo imobili\u00e1rio da Warren e descubra por que investir"},"content":{"rendered":"\n<p>Em r\u00e1pida expans\u00e3o nos \u00faltimos anos, saindo de 200 mil investidores em 2018 para 2 milh\u00f5es em 2022, o mercado de fundos imobili\u00e1rios acaba de receber um novo protagonista.<\/p>\n\n\n\n<p>Desde o \u00faltimo dia 31 de outubro, est\u00e1 listado na <a href=\"https:\/\/warren.com.br\/magazine\/bolsa-de-valores-como-funciona\/\">Bolsa de Valores<\/a> o <a href=\"https:\/\/warren.com.br\/magazine\/tipos-de-fundos-imobiliarios\/\">fundo imobili\u00e1rio<\/a> <strong>Warren Securities<\/strong>, sob o c\u00f3digo <strong>WSEC11<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh6.googleusercontent.com\/E84APwXkrf1YnMM9arJPD_tqDCJIf-clnkVLy2fp8aC_Tk77BJKff0Y3hpKVuJ83l5iGhFzPVvv6p3No4Xj6wwS0iJIfRE2_5uJxzdimpWihKIoj6e32pqkQRZFY-8VVcolvn4BNJEUNLS2yBPooRa5CmpH_7-hPSe6VC2kBOpsdV43lxW6-CX0kGjhLiA\" alt=\"\"\/><figcaption class=\"wp-element-caption\">Evento de lan\u00e7amento do fundo na B3.<\/figcaption><\/figure>\n\n\n\n<p>Trata-se do <strong>primeiro fundo imobili\u00e1rio da Warren<\/strong>: al\u00e9m da gest\u00e3o da Warren Asset, frente liderada por<strong> <\/strong>Igor Cavaca, o fundo conta com a expertise da \u00e1rea de Gustavo Kosnitzer, nosso Head de Mercado de Capitais.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/dLE74aIg9HJu2E5EE-YSiQEcB74K01_4oOTA4ZfZlJobt_t2scbxt40Z3RJlO4VIn2LHvykSW329O25Kpq2iWW2MYn2xU35_ukfyv9cNIkSH2BS5hbLaQX9gRfDoOYBbfw0jMt1arOdqyFvz92Rr-d1rUUr5MZeiLgX6V47Y3UVQn_UjPwC5kn5cZWfxkw\" alt=\"\"\/><figcaption class=\"wp-element-caption\">Igor Cavaca, head de Gest\u00e3o de Investimentos na Warren Asset Management.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/7PXKDg-RzcbvxCR4v692Y3qtcQy-5SFauOYrIaHgoD4edFu_37sQcZO0MuFBIiHbIGrY0IR46v5caO5EvzwUGWPMjGGxkS0RgQhP7Dx06bG1lSvAfFXQQResSKClqvhR-lKEC6XlRaiDM9krZhxYjjPHV5geKJ0LUuW67wdHsiqbrK28S9pZ3p05QRDcTw\" alt=\"\"\/><figcaption class=\"wp-element-caption\"> Gustavo Kosnitzer, head de Mercado de Capitais.<\/figcaption><\/figure>\n\n\n\n<p>Mas por que a Warren decidiu criar o seu FII e quais s\u00e3o os diferenciais que justificam o investimento no ativo?&nbsp;<\/p>\n\n\n\n<p>\u00c9 isso que vamos explicar nesse artigo. Confira.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Indice<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a04984dacc99\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a04984dacc99\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/#O_que_e_o_WSEC11\" >O que \u00e9 o WSEC11?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/#Por_que_investir_no_WSEC11\" >Por que investir no WSEC11?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/#E_o_momento_de_investir_em_FIIs_de_papel\" >\u00c9 o momento de investir em FIIs de papel?<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/#Dividendos_recorrentes\" >Dividendos recorrentes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/#Rendimentos_isentos_de_imposto\" >Rendimentos isentos de imposto<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/#Liquidez_do_mercado\" >Liquidez do mercado<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/#Possivel_queda_da_Selic_no_medio_prazo\" >Poss\u00edvel queda da Selic no m\u00e9dio prazo<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/#As_vantagens_do_WSEC11\" >As vantagens do WSEC11<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/#Experiencia_da_Warren_no_mercado_imobiliario\" >Experi\u00eancia da Warren no mercado imobili\u00e1rio<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/#Gestao_ativa_da_Warren_Asset\" >Gest\u00e3o ativa da Warren Asset<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/#Diversificacao_do_fundo\" >Diversifica\u00e7\u00e3o do fundo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/#Modelo_de_investimento_transparente\" >Modelo de investimento transparente<\/a><\/li><\/ul><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/#Informacoes_tecnicas_sobre_o_WSEC11\" >Informa\u00e7\u00f5es t\u00e9cnicas sobre o WSEC11<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/#Como_investir_no_WSEC11\" >Como investir no WSEC11?<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"O_que_e_o_WSEC11\"><\/span>O que \u00e9 o WSEC11?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>O WSEC11 \u00e9 um <strong>fundo imobili\u00e1rio de papel<\/strong>, que investe preferencialmente em <strong>opera\u00e7\u00f5es de cr\u00e9dito com lastro imobili\u00e1rio<\/strong>.<\/p>\n\n\n\n<p>A experi\u00eancia de d\u00e9cadas no mercado imobili\u00e1rio se junta \u00e0 tecnologia de gest\u00e3o de fundos da Warren para criar um FII que tem como objetivo ser um dos principais fundos de cr\u00e9dito imobili\u00e1rio do mercado.&nbsp;&nbsp;<\/p>\n\n\n\n<p>O resultado vir\u00e1 de uma estrat\u00e9gia s\u00f3lida, com sele\u00e7\u00e3o criteriosa de ativos que priorizam um pr\u00eamio de rentabilidade em rela\u00e7\u00e3o ao <a href=\"https:\/\/warren.com.br\/magazine\/cdi-hoje\/\">CDI<\/a>, com a seguran\u00e7a derivada do nosso processo de gest\u00e3o e das garantias exigidas.&nbsp;<\/p>\n\n\n\n<p>\u201cHistoricamente, o brasileiro tem a cultura de investir em im\u00f3veis, mas vem descobrindo os Fundos Imobili\u00e1rios como uma alternativa muito mais vantajosa\u201d, observa Gustavo.<\/p>\n\n\n\n<p>\u201cOs fundos imobili\u00e1rios s\u00e3o o ve\u00edculo mais eficiente para acessar este mercado pelas in\u00fameras vantagens que apresenta: dividendos mensais, isen\u00e7\u00e3o IR nos rendimentos, diversifica\u00e7\u00e3o, liquidez&nbsp; e gest\u00e3o profissional&#8221;, destaca.&nbsp;<\/p>\n\n\n\n<p><strong>LEIA MAIS | <\/strong><a href=\"https:\/\/warren.com.br\/magazine\/cdi\/\"><strong>CDI: o que \u00e9, como \u00e9 calculado e por que afeta seus investimentos<\/strong><\/a><strong>&nbsp;<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Por_que_investir_no_WSEC11\"><\/span>Por que investir no WSEC11?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Faz sentido dividir os argumentos em duas se\u00e7\u00f5es.<\/p>\n\n\n\n<p>A primeira, na qual vamos nos aprofundar agora, \u00e9 mais gen\u00e9rica: abrange fundos imobili\u00e1rios de papel e suas caracter\u00edsticas.<\/p>\n\n\n\n<p>A segunda, fala especificamente das vantagens do WSEC11 quando comparado aos mais de 400 FIIs dispon\u00edveis hoje no mercado.&nbsp;<\/p>\n\n\n\n<p>Vamos l\u00e1?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"E_o_momento_de_investir_em_FIIs_de_papel\"><\/span>\u00c9 o momento de investir em FIIs de papel?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Os Fundos Imobili\u00e1rios (FIIs) do tipo &#8220;papel&#8221; s\u00e3o assim chamados por serem Fundos de Investimentos que aplicam o dinheiro de seus cotistas em opera\u00e7\u00f5es de cr\u00e9dito com lastro imobili\u00e1rio.<\/p>\n\n\n\n<p>Entenda por que consideramos os investimentos em FIIs uma boa escolha.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Dividendos_recorrentes\"><\/span>Dividendos recorrentes<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Investir em FIIs \u00e9 uma forma de obter <strong>renda passiva mensal<\/strong>.&nbsp;<\/p>\n\n\n\n<p>Conforme a legisla\u00e7\u00e3o, os FIIs t\u00eam a obrigatoriedade de <strong>distribuir um m\u00ednimo de 95% do seu resultado<\/strong>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Rendimentos_isentos_de_imposto\"><\/span>Rendimentos isentos de imposto<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Essa \u00e9 outra grande vantagem de investir em FIIs: os dividendos s\u00e3o isentos de Imposto de Renda.<\/p>\n\n\n\n<p>Ou seja,a distribui\u00e7\u00e3o de resultados <strong>n\u00e3o ser\u00e1 reduzida pela tributa\u00e7\u00e3o<\/strong>.<\/p>\n\n\n\n<p>Vale lembrar que, mesmo com a isen\u00e7\u00e3o, \u00e9 necess\u00e1rio informar os rendimentos ao realizar a declara\u00e7\u00e3o anual do IR.<\/p>\n\n\n\n<p><strong>LEIA MAIS | <\/strong><a href=\"https:\/\/warren.com.br\/magazine\/geracao-prateada-no-que-investir\/\"><strong>A gera\u00e7\u00e3o prateada e a aposentadoria: no que investir para aproveitar a fase da melhor forma?<\/strong><\/a><strong>&nbsp;<\/strong><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Liquidez_do_mercado\"><\/span>Liquidez do mercado<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p><a href=\"https:\/\/warren.com.br\/magazine\/liquidez\/\">Liquidez<\/a> \u00e9 a facilidade com que voc\u00ea consegue vender ou resgatar um ativo.&nbsp;<\/p>\n\n\n\n<p>As cotas dos fundos imobili\u00e1rios s\u00e3o negociadas em bolsa, ent\u00e3o voc\u00ea pode vender ou comprar uma cota diretamente do seu home broker.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Possivel_queda_da_Selic_no_medio_prazo\"><\/span>Poss\u00edvel queda da Selic no m\u00e9dio prazo<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Se voc\u00ea \u00e9 daquelas pessoas que pensam em investir em FIIs pela seguran\u00e7a, provavelmente, j\u00e1 surgiu a d\u00favida: \u201cqual \u00e9 melhor momento de se investir em FIIs?\u201d.<\/p>\n\n\n\n<p>Talvez voc\u00ea se lembre que em 2020, durante a pandemia, a <a href=\"https:\/\/warren.com.br\/magazine\/taxa-selic\/\">Taxa Selic<\/a> chegou a <a href=\"https:\/\/warren.com.br\/magazine\/nova-queda-selic-entenda-impactos-renda-fixa\/\">2%<\/a> a.a, menor patamar da hist\u00f3ria.<\/p>\n\n\n\n<p>Com a alta da <a href=\"https:\/\/warren.com.br\/magazine\/taxa-selic-inflacao\/\">infla\u00e7\u00e3o,<\/a> a taxa voltou a subir e hoje encontra-se em <a href=\"https:\/\/warren.com.br\/magazine\/taxa-selic-hoje\/\">13,75% a.a<\/a>.<\/p>\n\n\n\n<p>Diante deste cen\u00e1rio, fica a d\u00favida se \u00e9 o momento adequado.<\/p>\n\n\n\n<p>Para Gustavo, considerando os movimentos c\u00edclicos do mercado, a tend\u00eancia \u00e9 que seja um excelente momento para se investir em FIIs.&nbsp;<\/p>\n\n\n\n<p>\u201cApesar do n\u00edvel elevado de taxa de juros do momento, o pr\u00eamio conseguido nos ativos de cr\u00e9dito que ir\u00e3o compor a carteira do fundo tamb\u00e9m tendem a ser acima dos patamares hist\u00f3ricos\u201d, acredita.<\/p>\n\n\n\n<p>Ele acrescenta que \u201ct\u00e3o logo se inicie a invers\u00e3o da curva de juros, com a redu\u00e7\u00e3o da Selic e queda do juro real no Brasil, haver\u00e1 tamb\u00e9m uma poss\u00edvel valoriza\u00e7\u00e3o no pre\u00e7o da cota dos FIIs. Assim, al\u00e9m dos dividendos mensais, o investidor ter\u00e1 tamb\u00e9m um ganho potencial patrimonial\u201d.<\/p>\n\n\n\n<p><strong>LEIA MAIS | <\/strong><a href=\"https:\/\/warren.com.br\/magazine\/investir-fiis-selic-em-alta\/\"><strong>Com a Selic em alta, por que investir em FIIs e n\u00e3o em renda fixa?<\/strong><\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"As_vantagens_do_WSEC11\"><\/span>As vantagens do WSEC11<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Agora que voc\u00ea j\u00e1 entendeu quais s\u00e3o as principais vantagens de investir em FIIs, voc\u00ea vai descobrir por que o fundo WSEC11 pode ser uma op\u00e7\u00e3o para voc\u00ea quando comparado a outros produtos da categoria.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Experiencia_da_Warren_no_mercado_imobiliario\"><\/span>Experi\u00eancia da Warren no mercado imobili\u00e1rio<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Ao longo dos \u00faltimos dois anos, a \u00e1rea de Mercados de Capitais da Warren fechou quase <strong>R$ 2 bilh\u00f5es em neg\u00f3cios<\/strong> nos setores imobili\u00e1rio e de infraestrutura.<\/p>\n\n\n\n<p>\u201cAssim como seremos a maior plataforma de investimento do Brasil, tamb\u00e9m seremos um player relevante de cr\u00e9dito e investimento imobili\u00e1rio via mercado de capitais, beneficiando tanto as empresas que necessitam de recursos como nossos clientes que ter\u00e3o acesso a investimentos exclusivos. Entre esses produtos est\u00e3o os fundos imobili\u00e1rios, como \u00e9 o caso do WSEC11\u201d, explica Gustavo.<\/p>\n\n\n\n<p><strong>LEIA MAIS | <\/strong><a href=\"https:\/\/warren.com.br\/magazine\/novo-passo-mercado-de-capitais\/\"><strong>Um novo passo para o mercado de capitais: os desafios da ind\u00fastria<\/strong><\/a><strong>&nbsp;<\/strong><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Gestao_ativa_da_Warren_Asset\"><\/span>Gest\u00e3o ativa da Warren Asset<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>A Warren Asset criou e administra mais de 20 fundos de <a href=\"https:\/\/warren.com.br\/magazine\/investimento-renda-fixa\/\">renda fixa<\/a>, <a href=\"https:\/\/warren.com.br\/magazine\/investimento-renda-variavel\/\">renda vari\u00e1vel<\/a>, multimercados e outros.<\/p>\n\n\n\n<p>A expertise do time se une \u00e0 tecnologia para oferecer produtos inovadores, com estrat\u00e9gias consistentes e capazes de aumentar a rentabilidade dos investidores.<\/p>\n\n\n\n<p>Al\u00e9m do diferencial estrat\u00e9gico, ao investir no fundo WSEC11, os cotistas contam com o servi\u00e7o de gest\u00e3o ativa.&nbsp;<\/p>\n\n\n\n<p>Isso significa que a gestora estar\u00e1 sempre atenta aos resultados do fundo e aos movimentos do mercado, podendo <strong>adequar a estrat\u00e9gia quando for oportuno<\/strong>.<\/p>\n\n\n\n<p>&#8220;Muitas casas n\u00e3o t\u00eam essa facilidade de fazer mudan\u00e7as nos ativos conforme o momento, porque a estrutura \u00e9 mais engessada e o uso da tecnologia \u00e9 menor. Aqui estamos sempre atentos para que os cotistas tenham acesso \u00e0s melhores oportunidades\u201d, declara Igor.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Diversificacao_do_fundo\"><\/span>Diversifica\u00e7\u00e3o do fundo<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>A <a href=\"https:\/\/warren.com.br\/magazine\/diversificacao-investimentos\/\">diversifica\u00e7\u00e3o<\/a> de um fundo \u00e9 essencial para a rentabilidade do investimento.<\/p>\n\n\n\n<p>No caso do WSEC11, a Warren Asset planejou uma carteira com ativos de cr\u00e9dito focados no mercado imobili\u00e1rio.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Modelo_de_investimento_transparente\"><\/span>Modelo de investimento transparente<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Na Warren, proporcionamos uma jornada investidora que \u00e9 livre de <a href=\"https:\/\/warren.com.br\/magazine\/como-os-conflitos-de-interesse-atrapalham-seus-investimentos\/\">conflito de interesses<\/a>.<\/p>\n\n\n\n<p>Voc\u00ea tem a seguran\u00e7a de saber que seu dinheiro est\u00e1 aplicado em produtos que s\u00e3o os melhores para voc\u00ea e seus <a href=\"https:\/\/warren.com.br\/magazine\/investimento-por-objetivos\/\">objetivos<\/a>.&nbsp;<\/p>\n\n\n\n<p>Vale lembrar que a Warren \u00e9 uma corretora de valores independente, ou seja, n\u00e3o est\u00e1 atrelada a bancos.<\/p>\n\n\n\n<p>Nosso foco \u00e9 oferecer produtos e servi\u00e7os que aumentam a rentabilidade do seu dinheiro de forma segura, adequados ao seu <a href=\"https:\/\/warren.com.br\/blog\/perfil-de-investidor\/\">perfil<\/a> e objetivos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Informacoes_tecnicas_sobre_o_WSEC11\"><\/span>Informa\u00e7\u00f5es t\u00e9cnicas sobre o WSEC11<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>A seguir, listamos as informa\u00e7\u00f5es mais t\u00e9cnicas relacionadas ao WSEC11. Confira:<\/p>\n\n\n\n<p><strong>Gestor<\/strong>: Warren Brasil Gest\u00e3o e Administra\u00e7\u00e3o de Recursos LTDA<br><strong>Administrador<\/strong>: Warren Corretora de Valores Mobili\u00e1rios e C\u00e2mbio LTDA<br><strong>Escriturador das cotas<\/strong>: Banco Daycoval<br><strong>Auditor<\/strong>: KPMG<br><strong>In\u00edcio do fundo<\/strong>: 13\/10\/2022<br><strong>Prazo do fundo<\/strong>: indeterminado<br><strong>Taxa de administra\u00e7\u00e3o<\/strong>: 1,00% a.a.<br><strong>Taxa de performance<\/strong>: 20% sobre o que exceder 110% da Taxa DI<br><strong>Distribui\u00e7\u00e3o de rendimentos<\/strong>: semestral, podendo ser mensal<br><strong>Rela\u00e7\u00f5es com investidores<\/strong>: <a href=\"mailto:gestao@warren.com.br\">gestao@warren.com.br<\/a><\/p>\n\n\n\n<p>Agora, vamos entender como investir no WSEC11 na pr\u00e1tica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como_investir_no_WSEC11\"><\/span>Como investir no WSEC11?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Como o WSEC11 est\u00e1 listado na bolsa de valores, voc\u00ea tem acesso ao FII em qualquer corretora de valores.<\/p>\n\n\n\n<p>Na nossa plataforma, voc\u00ea investe no WSEC11 pela aba Bolsa. Basta abrir sua conta, acessar a aba Bolsa e buscar pelo c\u00f3digo \u201cWSEC11\u201d. Depois, \u00e9 s\u00f3 escolher a quantidade de cotas, de acordo com o valor do seu investimento.<\/p>\n\n\n\n<p>Vale lembrar que por ser um produto de investimento listado na Bolsa, voc\u00ea pode investir por meio de outras plataformas.<\/p>\n\n\n\n<p>Quer falar com um dos nossos especialistas? Preencha o formul\u00e1rio abaixo que entraremos em contato:<\/p>\n\n\n<script charset=\"utf-8\" type=\"text\/javascript\" src=\"\/\/js.hsforms.net\/forms\/v2.js\"><\/script><script>\n\t\thbspt.forms.create({\n\t\tregion: \"na1\",\n\t\tportalId: \"5032423\",\n\t\tformId: \"809ecdba-04e1-4a5c-b710-02c0583cd9d3\",\n\t\tversion: \"V2_PRERELEASE\"\n\t\t});\n\t\t<\/script>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>Conte\u00fados recomendados para voc\u00ea:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/warren.com.br\/magazine\/escritorio-warren-sao-paulo\/\">Warren inaugura novo escrit\u00f3rio em S\u00e3o Paulo, na Faria Lima<\/a>&nbsp;<\/li>\n\n\n\n<li><a href=\"https:\/\/warren.com.br\/magazine\/ferramentas-analise-comparacao-fundos\/\">Warren lan\u00e7a ferramentas para an\u00e1lise e compara\u00e7\u00e3o de fundos de investimentos<\/a>&nbsp;<\/li>\n\n\n\n<li><a href=\"https:\/\/warren.com.br\/magazine\/dia-do-cliente-2022\/\">Entenda o que significa, na pr\u00e1tica, colocar o cliente no centro das decis\u00f5es<\/a>&nbsp;<\/li>\n\n\n\n<li><a href=\"https:\/\/warren.com.br\/magazine\/nyse-warren-internacional\/\">Fundadores da Warren d\u00e3o entrevista \u00e0 NYSE em mais um passo rumo \u00e0 Warren Internacional<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/warren.com.br\/magazine\/warren-venus-100-milhoes\/\">Fundo Warren V\u00eanus atinge R$ 100 milh\u00f5es de patrim\u00f4nio sob gest\u00e3o<\/a><\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em r\u00e1pida expans\u00e3o nos \u00faltimos anos, saindo de 200 mil investidores em 2018 para 2 milh\u00f5es em 2022, o mercado de fundos imobili\u00e1rios acaba de receber um novo protagonista.<\/p>\n","protected":false},"author":8,"featured_media":20868,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[752],"tags":[],"class_list":["post-20861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-warren","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WSEC11: conhe\u00e7a o primeiro fundo imobili\u00e1rio da Warren e descubra por que investir<\/title>\n<meta name=\"description\" content=\"Desde o \u00faltimo dia 31 de outubro, est\u00e1 listado na Bolsa de Valores o fundo imobili\u00e1rio Warren Securities, sob o c\u00f3digo WSEC11. Saiba os detalhes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WSEC11: conhe\u00e7a o primeiro fundo imobili\u00e1rio da Warren e descubra por que investir\" \/>\n<meta property=\"og:description\" content=\"Desde o \u00faltimo dia 31 de outubro, est\u00e1 listado na Bolsa de Valores o fundo imobili\u00e1rio Warren Securities, sob o c\u00f3digo WSEC11. Saiba os detalhes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/\" \/>\n<meta property=\"og:site_name\" content=\"Warren Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/warrenbrasil\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-17T14:08:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-03T01:15:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/warren.com.br\/magazine\/wp-content\/uploads\/2022\/11\/ft18_warrenmagazine.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o Warren\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@warrenbrasil\" \/>\n<meta name=\"twitter:site\" content=\"@warrenbrasil\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o Warren\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WSEC11: conhe\u00e7a o primeiro fundo imobili\u00e1rio da Warren e descubra por que investir","description":"Desde o \u00faltimo dia 31 de outubro, est\u00e1 listado na Bolsa de Valores o fundo imobili\u00e1rio Warren Securities, sob o c\u00f3digo WSEC11. Saiba os detalhes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/","og_locale":"pt_BR","og_type":"article","og_title":"WSEC11: conhe\u00e7a o primeiro fundo imobili\u00e1rio da Warren e descubra por que investir","og_description":"Desde o \u00faltimo dia 31 de outubro, est\u00e1 listado na Bolsa de Valores o fundo imobili\u00e1rio Warren Securities, sob o c\u00f3digo WSEC11. Saiba os detalhes.","og_url":"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/","og_site_name":"Warren Magazine","article_publisher":"https:\/\/www.facebook.com\/warrenbrasil\/","article_published_time":"2022-11-17T14:08:26+00:00","article_modified_time":"2023-08-03T01:15:39+00:00","og_image":[{"width":1800,"height":1225,"url":"https:\/\/warren.com.br\/magazine\/wp-content\/uploads\/2022\/11\/ft18_warrenmagazine.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o Warren","twitter_card":"summary_large_image","twitter_creator":"@warrenbrasil","twitter_site":"@warrenbrasil","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o Warren","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/#article","isPartOf":{"@id":"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/"},"author":{"name":"Reda\u00e7\u00e3o Warren","@id":"https:\/\/warren.com.br\/magazine\/#\/schema\/person\/6ab5c3002c3fbf4a167e69ed8a2b228c"},"headline":"WSEC11: conhe\u00e7a o primeiro fundo imobili\u00e1rio da Warren e descubra por que investir","datePublished":"2022-11-17T14:08:26+00:00","dateModified":"2023-08-03T01:15:39+00:00","mainEntityOfPage":{"@id":"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/"},"wordCount":1519,"publisher":{"@id":"https:\/\/warren.com.br\/magazine\/#organization"},"image":{"@id":"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/#primaryimage"},"thumbnailUrl":"https:\/\/warren.com.br\/magazine\/wp-content\/uploads\/2022\/11\/ft18_warrenmagazine.jpg","articleSection":["A Warren\u00a0"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/","url":"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/","name":"WSEC11: conhe\u00e7a o primeiro fundo imobili\u00e1rio da Warren e descubra por que investir","isPartOf":{"@id":"https:\/\/warren.com.br\/magazine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/#primaryimage"},"image":{"@id":"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/#primaryimage"},"thumbnailUrl":"https:\/\/warren.com.br\/magazine\/wp-content\/uploads\/2022\/11\/ft18_warrenmagazine.jpg","datePublished":"2022-11-17T14:08:26+00:00","dateModified":"2023-08-03T01:15:39+00:00","description":"Desde o \u00faltimo dia 31 de outubro, est\u00e1 listado na Bolsa de Valores o fundo imobili\u00e1rio Warren Securities, sob o c\u00f3digo WSEC11. Saiba os detalhes.","inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/warren.com.br\/magazine\/wsec11-fii-warren\/#primaryimage","url":"https:\/\/warren.com.br\/magazine\/wp-content\/uploads\/2022\/11\/ft18_warrenmagazine.jpg","contentUrl":"https:\/\/warren.com.br\/magazine\/wp-content\/uploads\/2022\/11\/ft18_warrenmagazine.jpg","width":1800,"height":1225,"caption":"WSEC11: conhe\u00e7a o primeiro fundo imobili\u00e1rio da Warren e descubra por que investir, ilustra\u00e7\u00e3o"},{"@type":"WebSite","@id":"https:\/\/warren.com.br\/magazine\/#website","url":"https:\/\/warren.com.br\/magazine\/","name":"Warren Magazine","description":"","publisher":{"@id":"https:\/\/warren.com.br\/magazine\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/warren.com.br\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/warren.com.br\/magazine\/#organization","name":"Warren Magazine","url":"https:\/\/warren.com.br\/magazine\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/warren.com.br\/magazine\/#\/schema\/logo\/image\/","url":"https:\/\/warren.com.br\/magazine\/wp-content\/uploads\/2023\/06\/ThumbMagazine.jpg","contentUrl":"https:\/\/warren.com.br\/magazine\/wp-content\/uploads\/2023\/06\/ThumbMagazine.jpg","width":2400,"height":1260,"caption":"Warren Magazine"},"image":{"@id":"https:\/\/warren.com.br\/magazine\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/warrenbrasil\/","https:\/\/x.com\/warrenbrasil","https:\/\/www.instagram.com\/warrenbrasil\/","https:\/\/www.linkedin.com\/company\/warrenbrasil\/","https:\/\/www.youtube.com\/channel\/UCqIO5twa50iGz2wT5cGS-XQ"]},{"@type":"Person","@id":"https:\/\/warren.com.br\/magazine\/#\/schema\/person\/6ab5c3002c3fbf4a167e69ed8a2b228c","name":"Reda\u00e7\u00e3o Warren","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/warren.com.br\/magazine\/wp-content\/uploads\/2023\/12\/Instagram-avatar-96x96.png","url":"https:\/\/warren.com.br\/magazine\/wp-content\/uploads\/2023\/12\/Instagram-avatar-96x96.png","contentUrl":"https:\/\/warren.com.br\/magazine\/wp-content\/uploads\/2023\/12\/Instagram-avatar-96x96.png","caption":"Reda\u00e7\u00e3o Warren"},"url":"https:\/\/warren.com.br\/magazine\/author\/redacao-warren\/"}]}},"_links":{"self":[{"href":"https:\/\/warren.com.br\/magazine\/wp-json\/wp\/v2\/posts\/20861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/warren.com.br\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/warren.com.br\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/warren.com.br\/magazine\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/warren.com.br\/magazine\/wp-json\/wp\/v2\/comments?post=20861"}],"version-history":[{"count":11,"href":"https:\/\/warren.com.br\/magazine\/wp-json\/wp\/v2\/posts\/20861\/revisions"}],"predecessor-version":[{"id":21877,"href":"https:\/\/warren.com.br\/magazine\/wp-json\/wp\/v2\/posts\/20861\/revisions\/21877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/warren.com.br\/magazine\/wp-json\/wp\/v2\/media\/20868"}],"wp:attachment":[{"href":"https:\/\/warren.com.br\/magazine\/wp-json\/wp\/v2\/media?parent=20861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/warren.com.br\/magazine\/wp-json\/wp\/v2\/categories?post=20861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/warren.com.br\/magazine\/wp-json\/wp\/v2\/tags?post=20861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}